{"id":198,"date":"2022-08-25T09:44:49","date_gmt":"2022-08-25T14:44:49","guid":{"rendered":"https:\/\/nestequip.com\/equipment\/?post_type=product&#038;p=198"},"modified":"2023-03-23T08:14:15","modified_gmt":"2023-03-23T13:14:15","slug":"2005-f550-pump-truck","status":"publish","type":"product","link":"https:\/\/nestequip.com\/equipment\/product\/2005-f550-pump-truck\/","title":{"rendered":"2005 F550 5T Pump Truck"},"content":{"rendered":"<p>2005 F550 Pump Truck<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Model-F550<\/p>\n<p>VIN-1FDAF57P35EA36791<\/p>\n<p>Pump Truck<\/p>\n<p>Year-2005<\/p>\n<p>Miles-75,490<\/p>\n","protected":false},"featured_media":505,"template":"","meta":[],"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":{"0":"post-198","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pump-trucks","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/product\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/media\/505"}],"wp:attachment":[{"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/product_brand?post=198"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/product_cat?post=198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nestequip.com\/equipment\/wp-json\/wp\/v2\/product_tag?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}